{"id":799,"count":3,"description":"","link":"https:\/\/doenges.com\/blog\/tag\/nacht?lang=de","name":"Nacht","slug":"nacht","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/doenges.com\/blog\/wp-json\/wp\/v2\/tags\/799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/doenges.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/doenges.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/doenges.com\/blog\/wp-json\/wp\/v2\/posts?tags=799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}