{"id":543,"count":1,"description":"","link":"https:\/\/doenges.com\/blog\/tag\/saxophon?lang=de","name":"Saxophon","slug":"saxophon","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/doenges.com\/blog\/wp-json\/wp\/v2\/tags\/543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/doenges.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/doenges.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/doenges.com\/blog\/wp-json\/wp\/v2\/posts?tags=543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}